{"id":913,"date":"2018-09-20T12:20:25","date_gmt":"2018-09-20T19:20:25","guid":{"rendered":"https:\/\/www.nestpresales.com\/blog\/?p=913"},"modified":"2019-02-05T12:16:54","modified_gmt":"2019-02-05T20:16:54","slug":"ovation-by-domus-homes","status":"publish","type":"post","link":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/","title":{"rendered":"Ovation by Domus Homes: VIP Previews available, Call now!"},"content":{"rendered":"<h1 style=\"text-align: center;\">Now booking VIP Previews on the gorgeous Ovation by Domus!<\/h1>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-914 size-large\" src=\"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2-1024x341.jpg\" alt=\"Ovation by Domus\" width=\"700\" height=\"233\" srcset=\"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2-1024x341.jpg 1024w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2-300x100.jpg 300w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2-768x256.jpg 768w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2.jpg 1920w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h2 style=\"text-align: center;\">Conveniently located near New West Skytrain Station and a short walk to the Esplanade and the Quay Market!<\/h2>\n<h4 style=\"text-align: center;\">Brought to you by Domus Homes!<\/h4>\n<div style=\"text-align: center;\"><a target=\"_blank\" href=\"https:\/\/www.nestpresales.com\/listings\/bldg-6556\/ovation-new-westminster-condo-penthouse-for-sale\" rel=\"noopener\">Register with Nest Presales now<\/a>\u00a0to secure your spot for the first ones to get access to ovation by domus!<\/div>\n<ul style=\"text-align: center;\">\n<li>Located at 813 Carnarvon (formerly Carnarvon Gardens and The Stage) in New Westminster<\/li>\n<li>Close to the New West Skytrain Station<\/li>\n<li>204 total suites<\/li>\n<li>Mixed use buildings &#8211; 32 storey concrete high-rise, a podium and a 6 storey low-rise<\/li>\n<li>Both commercial and offices on lower levels<\/li>\n<li>50 non-market rental (seniors) suites for the Performing Arts Lodge (PAL) which will be located in the low-rise<\/li>\n<li>One, two and three bedroom flats and two level townhomes available<\/li>\n<\/ul>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-915 size-large aligncenter\" src=\"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-1024x667.jpg\" alt=\"Ovation by Domus\" width=\"700\" height=\"456\" srcset=\"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-1024x667.jpg 1024w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-300x195.jpg 300w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-768x500.jpg 768w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation.jpg 1920w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><strong>Building Amenities:<\/strong><\/p>\n<ul>\n<li>kids play area<\/li>\n<li>indoor and outdoor amenity space<\/li>\n<li>rooftop garden<\/li>\n<li>all suites come with a parking stall (except B plan)<\/li>\n<\/ul>\n<\/div>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-916 size-large\" src=\"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation1-1024x350.jpg\" alt=\"Ovation by Domus\" width=\"700\" height=\"239\" srcset=\"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation1-1024x350.jpg 1024w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation1-300x103.jpg 300w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation1-768x263.jpg 768w, https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation1.jpg 1919w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<div style=\"text-align: center;\"><a target=\"_blank\" href=\"https:\/\/www.nestpresales.com\/listings\/bldg-6556\/ovation-new-westminster-condo-penthouse-for-sale\" rel=\"noopener\"><b>Click Here To Register for Units, Floorplans and Prices at The Ovation (813 Carnarvon Street, New Westminster, BC)<\/b><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>The Ovation located near New West Skytrain Station and a short walk to the Esplanade and the Quay Market in New Westminster. This mixed use buildings &#8211; 32 storey concrete high-rise, a podium and a 6 storey low-rise will host both commercial and offices, condos, and two level townhomes. Don&#8217;t miss out on these gorgeous properties! VIP Previews on now! <\/p>\n","protected":false},"author":2,"featured_media":914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,27,132],"tags":[189,8,78,224,242,223,244,35,243,59,213],"class_list":["post-913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-condo-presales","category-new-developments","category-townhome-presales","tag-concrete","tag-condo-presales","tag-condos","tag-downtown-new-west","tag-high-rise-high-rise","tag-new-west-quay","tag-new-west-skytrain","tag-new-westminster","tag-rooftop-garden","tag-townhome","tag-townhome-presales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ovation by Domus Homes: VIP Previews available, Call now!<\/title>\n<meta name=\"description\" content=\"Luxury townhomes &amp; condos presaleat Ovation by Domus in New Westminster near New West Skytrain and Quay Market. Contact us Today\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ovation by Domus Homes: VIP Previews available, Call now!\" \/>\n<meta property=\"og:description\" content=\"Luxury townhomes &amp; condos presaleat Ovation by Domus in New Westminster near New West Skytrain and Quay Market. Contact us Today\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/\" \/>\n<meta property=\"og:site_name\" content=\"Nest Presales Real Estate Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nestpresales\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-20T19:20:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-05T20:16:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nest Presales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nest Presales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/\"},\"author\":{\"name\":\"Nest Presales\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#\\\/schema\\\/person\\\/740873dae446f51a1f78a616553dd7dc\"},\"headline\":\"Ovation by Domus Homes: VIP Previews available, Call now!\",\"datePublished\":\"2018-09-20T19:20:25+00:00\",\"dateModified\":\"2019-02-05T20:16:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/\"},\"wordCount\":171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/ovation-2.jpg\",\"keywords\":[\"concrete\",\"Condo Presales\",\"Condos\",\"downtown new west\",\"high-rise high-rise\",\"new west quay\",\"new west skytrain\",\"New Westminster\",\"rooftop garden\",\"Townhome\",\"Townhome Presales\"],\"articleSection\":[\"Condo Presales\",\"New Developments\",\"Townhome Presales\"],\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/\",\"url\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/\",\"name\":\"Ovation by Domus Homes: VIP Previews available, Call now!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/ovation-2.jpg\",\"datePublished\":\"2018-09-20T19:20:25+00:00\",\"dateModified\":\"2019-02-05T20:16:54+00:00\",\"description\":\"Luxury townhomes & condos presaleat Ovation by Domus in New Westminster near New West Skytrain and Quay Market. Contact us Today\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/ovation-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/ovation-2.jpg\",\"width\":1920,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/ovation-by-domus-homes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ovation by Domus Homes: VIP Previews available, Call now!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/\",\"name\":\"Nest Presales Real Estate Blog\",\"description\":\"Vancouver and Victoria Presales\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#organization\",\"name\":\"Nest Presales - Vancouver Presale Condos and Townhomes\",\"url\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/branding01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/branding01.jpg\",\"width\":960,\"height\":600,\"caption\":\"Nest Presales - Vancouver Presale Condos and Townhomes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nestpresales\\\/\",\"https:\\\/\\\/www.instagram.com\\\/nestpresales\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/#\\\/schema\\\/person\\\/740873dae446f51a1f78a616553dd7dc\",\"name\":\"Nest Presales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29b47085618fe2caeb2f2ec4b9a4b157afaef93ab71f66b10f856a051ec8c500?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29b47085618fe2caeb2f2ec4b9a4b157afaef93ab71f66b10f856a051ec8c500?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/29b47085618fe2caeb2f2ec4b9a4b157afaef93ab71f66b10f856a051ec8c500?s=96&d=mm&r=g\",\"caption\":\"Nest Presales\"},\"url\":\"https:\\\/\\\/www.nestpresales.com\\\/blog\\\/author\\\/nest_presales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ovation by Domus Homes: VIP Previews available, Call now!","description":"Luxury townhomes & condos presaleat Ovation by Domus in New Westminster near New West Skytrain and Quay Market. Contact us Today","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/","og_locale":"en_US","og_type":"article","og_title":"Ovation by Domus Homes: VIP Previews available, Call now!","og_description":"Luxury townhomes & condos presaleat Ovation by Domus in New Westminster near New West Skytrain and Quay Market. Contact us Today","og_url":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/","og_site_name":"Nest Presales Real Estate Blog","article_publisher":"https:\/\/www.facebook.com\/nestpresales\/","article_published_time":"2018-09-20T19:20:25+00:00","article_modified_time":"2019-02-05T20:16:54+00:00","og_image":[{"width":1920,"height":640,"url":"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2.jpg","type":"image\/jpeg"}],"author":"Nest Presales","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nest Presales","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#article","isPartOf":{"@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/"},"author":{"name":"Nest Presales","@id":"https:\/\/www.nestpresales.com\/blog\/#\/schema\/person\/740873dae446f51a1f78a616553dd7dc"},"headline":"Ovation by Domus Homes: VIP Previews available, Call now!","datePublished":"2018-09-20T19:20:25+00:00","dateModified":"2019-02-05T20:16:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/"},"wordCount":171,"commentCount":0,"publisher":{"@id":"https:\/\/www.nestpresales.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2.jpg","keywords":["concrete","Condo Presales","Condos","downtown new west","high-rise high-rise","new west quay","new west skytrain","New Westminster","rooftop garden","Townhome","Townhome Presales"],"articleSection":["Condo Presales","New Developments","Townhome Presales"],"inLanguage":"en-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/","url":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/","name":"Ovation by Domus Homes: VIP Previews available, Call now!","isPartOf":{"@id":"https:\/\/www.nestpresales.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#primaryimage"},"image":{"@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2.jpg","datePublished":"2018-09-20T19:20:25+00:00","dateModified":"2019-02-05T20:16:54+00:00","description":"Luxury townhomes & condos presaleat Ovation by Domus in New Westminster near New West Skytrain and Quay Market. Contact us Today","breadcrumb":{"@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#primaryimage","url":"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2.jpg","contentUrl":"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2018\/09\/ovation-2.jpg","width":1920,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.nestpresales.com\/blog\/ovation-by-domus-homes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nestpresales.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ovation by Domus Homes: VIP Previews available, Call now!"}]},{"@type":"WebSite","@id":"https:\/\/www.nestpresales.com\/blog\/#website","url":"https:\/\/www.nestpresales.com\/blog\/","name":"Nest Presales Real Estate Blog","description":"Vancouver and Victoria Presales","publisher":{"@id":"https:\/\/www.nestpresales.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nestpresales.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/www.nestpresales.com\/blog\/#organization","name":"Nest Presales - Vancouver Presale Condos and Townhomes","url":"https:\/\/www.nestpresales.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.nestpresales.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2017\/12\/branding01.jpg","contentUrl":"https:\/\/www.nestpresales.com\/blog\/wp-content\/uploads\/2017\/12\/branding01.jpg","width":960,"height":600,"caption":"Nest Presales - Vancouver Presale Condos and Townhomes"},"image":{"@id":"https:\/\/www.nestpresales.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nestpresales\/","https:\/\/www.instagram.com\/nestpresales\/"]},{"@type":"Person","@id":"https:\/\/www.nestpresales.com\/blog\/#\/schema\/person\/740873dae446f51a1f78a616553dd7dc","name":"Nest Presales","image":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/29b47085618fe2caeb2f2ec4b9a4b157afaef93ab71f66b10f856a051ec8c500?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/29b47085618fe2caeb2f2ec4b9a4b157afaef93ab71f66b10f856a051ec8c500?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29b47085618fe2caeb2f2ec4b9a4b157afaef93ab71f66b10f856a051ec8c500?s=96&d=mm&r=g","caption":"Nest Presales"},"url":"https:\/\/www.nestpresales.com\/blog\/author\/nest_presales\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/posts\/913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/comments?post=913"}],"version-history":[{"count":5,"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/posts\/913\/revisions"}],"predecessor-version":[{"id":1111,"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/posts\/913\/revisions\/1111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/media\/914"}],"wp:attachment":[{"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/media?parent=913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/categories?post=913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nestpresales.com\/blog\/wp-json\/wp\/v2\/tags?post=913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}